{"id":7,"date":"2015-04-02T10:38:02","date_gmt":"2015-04-02T08:38:02","guid":{"rendered":"http:\/\/adnid.com\/blog\/?p=7"},"modified":"2023-08-02T13:02:55","modified_gmt":"2023-08-02T11:02:55","slug":"nueva-normativa-clp","status":"publish","type":"post","link":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/","title":{"rendered":"Adaptaci\u00f3n del sector a la nueva normativa CLP"},"content":{"rendered":"<table width=\"936\">\n<tbody>\n<tr>\n<td>A partir del 1 de junio de 2015, el Reglamento sobre clasificaci\u00f3n, etiquetado y envasado (CLP) ser\u00e1 el \u00fanico texto legislativo aplicable a la clasificaci\u00f3n y el etiquetado de las sustancias y las mezclas. En virtud del CLP, las empresas deber\u00e1n clasificar, etiquetar y envasar adecuadamente sus sustancias qu\u00edmicas peligrosas antes de comercializarlas.<\/p>\n<p>Si su empresa suministra productos qu\u00edmicos peligrosos dentro de la UE, debe etiquetarlos conforme al Reglamento de clasificaci\u00f3n, etiquetado y envasado (CLP). Los requisitos del Reglamento CLP garantizan que los peligros que representan los productos qu\u00edmicos se comuniquen de forma clara a los trabajadores y consumidores de la Uni\u00f3n Europea mediante una adecuada clasificaci\u00f3n y etiquetado.<\/p>\n<p>En resumen, el cumplimiento obligado del reglamento CLP, el cambio de sistema de clasificaci\u00f3n y etiquetado y la notificaci\u00f3n de las fichas toxicol\u00f3gicas constituyen&nbsp;<strong>un nuevo marco legislativo para el sector qu\u00edmico. Las obligaciones en materia de seguridad crecen, tambi\u00e9n las gestiones y su operativa<\/strong>.<strong>Nuevos retos para los que las empresas del sector qu\u00edmico deben preparase<\/strong>: con conocimiento, con personal especializado y con herramientas inform\u00e1ticas que aseguren y faciliten la gesti\u00f3n y cumplimiento de la normativa. La cuenta atr\u00e1s ya ha empezado\u2026<\/p>\n<p><strong>NUESTRA SOLUCI\u00d3N<\/strong><\/p>\n<figure style=\"width: 624px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full\" src=\"https:\/\/adnid.com\/img\/cms\/eqgest.jpg\" width=\"624\" height=\"174\"><figcaption class=\"wp-caption-text\">EQGest Software<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h4>Adaptaci\u00f3n r\u00e1pida y segura de su empresa a la normativa vigente sobre productos qu\u00edmicos.<\/h4>\n<p>Presentamos nuestra soluci\u00f3n IT, desarrollada para facilitar a las empresas del sector las gestiones en temas de seguridad y ayudarles a asegurar el cumplimiento de la normativa.<\/p>\n<p>Si quieres saber m\u00e1s sobre el Software de EQGEST y cumplir con las normativas vaya a:<\/p>\n<p><a class=\"btn btn-default\" href=\"https:\/\/adnid.com\/brand\/eqgest\" target=\"_blank\" rel=\"noopener noreferrer\">EQGEST<\/a><\/p>\n<p><strong>PARA M\u00c1S INFORMACI\u00d3N&nbsp;<a href=\"https:\/\/adnid.com\/content\/contactar\" target=\"_blank\" rel=\"noopener noreferrer\">CONTACTE CON ADNid<\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>A partir del 1 de junio de 2015, el Reglamento sobre clasificaci\u00f3n, etiquetado y envasado (CLP) ser\u00e1 el \u00fanico texto legislativo aplicable a la clasificaci\u00f3n y el etiquetado de las sustancias y las mezclas. En virtud del CLP, las empresas deber\u00e1n clasificar, etiquetar y envasar adecuadamente sus sustancias qu\u00edmicas peligrosas antes de comercializarlas. Si su [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":5733,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[246],"tags":[351,355],"class_list":["post-7","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","tag-certificaciones-y-estandares","tag-etiquetado-quimico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adaptaci\u00f3n del sector a la nueva normativa CLP | ADNID<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adaptaci\u00f3n del sector a la nueva normativa CLP | ADNID\" \/>\n<meta property=\"og:description\" content=\"A partir del 1 de junio de 2015, el Reglamento sobre clasificaci\u00f3n, etiquetado y envasado (CLP) ser\u00e1 el \u00fanico texto legislativo aplicable a la clasificaci\u00f3n y el etiquetado de las sustancias y las mezclas. En virtud del CLP, las empresas deber\u00e1n clasificar, etiquetar y envasar adecuadamente sus sustancias qu\u00edmicas peligrosas antes de comercializarlas. Si su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/\" \/>\n<meta property=\"og:site_name\" content=\"ADNID\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-02T08:38:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-02T11:02:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adnid.com\/blog\/wp-content\/uploads\/2015\/04\/normativa-CLP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n ADNid\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n ADNid\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adaptaci\u00f3n del sector a la nueva normativa CLP | ADNID","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/","og_locale":"es_ES","og_type":"article","og_title":"Adaptaci\u00f3n del sector a la nueva normativa CLP | ADNID","og_description":"A partir del 1 de junio de 2015, el Reglamento sobre clasificaci\u00f3n, etiquetado y envasado (CLP) ser\u00e1 el \u00fanico texto legislativo aplicable a la clasificaci\u00f3n y el etiquetado de las sustancias y las mezclas. En virtud del CLP, las empresas deber\u00e1n clasificar, etiquetar y envasar adecuadamente sus sustancias qu\u00edmicas peligrosas antes de comercializarlas. Si su [&hellip;]","og_url":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/","og_site_name":"ADNID","article_published_time":"2015-04-02T08:38:02+00:00","article_modified_time":"2023-08-02T11:02:55+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/adnid.com\/blog\/wp-content\/uploads\/2015\/04\/normativa-CLP.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n ADNid","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacci\u00f3n ADNid","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/#article","isPartOf":{"@id":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/"},"author":{"name":"Redacci\u00f3n ADNid","@id":"https:\/\/adnid.com\/blog\/#\/schema\/person\/f6037a86d189ccc3687f07085cf873b8"},"headline":"Adaptaci\u00f3n del sector a la nueva normativa CLP","datePublished":"2015-04-02T08:38:02+00:00","dateModified":"2023-08-02T11:02:55+00:00","mainEntityOfPage":{"@id":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/"},"wordCount":302,"commentCount":0,"publisher":{"@id":"https:\/\/adnid.com\/blog\/#organization"},"image":{"@id":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/#primaryimage"},"thumbnailUrl":"https:\/\/adnid.com\/blog\/wp-content\/uploads\/2015\/04\/normativa-CLP.jpg","keywords":["Certificaciones y est\u00e1ndares","Etiquetado qu\u00edmico"],"articleSection":["Art\u00edculos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/adnid.com\/blog\/nueva-normativa-clp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/","url":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/","name":"Adaptaci\u00f3n del sector a la nueva normativa CLP | ADNID","isPartOf":{"@id":"https:\/\/adnid.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/#primaryimage"},"image":{"@id":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/#primaryimage"},"thumbnailUrl":"https:\/\/adnid.com\/blog\/wp-content\/uploads\/2015\/04\/normativa-CLP.jpg","datePublished":"2015-04-02T08:38:02+00:00","dateModified":"2023-08-02T11:02:55+00:00","breadcrumb":{"@id":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adnid.com\/blog\/nueva-normativa-clp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/#primaryimage","url":"https:\/\/adnid.com\/blog\/wp-content\/uploads\/2015\/04\/normativa-CLP.jpg","contentUrl":"https:\/\/adnid.com\/blog\/wp-content\/uploads\/2015\/04\/normativa-CLP.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/adnid.com\/blog\/nueva-normativa-clp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/adnid.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Adaptaci\u00f3n del sector a la nueva normativa CLP"}]},{"@type":"WebSite","@id":"https:\/\/adnid.com\/blog\/#website","url":"https:\/\/adnid.com\/blog\/","name":"ADNID","description":"Labeling &amp; AIDC &amp; POS","publisher":{"@id":"https:\/\/adnid.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adnid.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/adnid.com\/blog\/#organization","name":"ADN Sistemas de Identificaci\u00f3n SL","url":"https:\/\/adnid.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adnid.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/adnid.com\/blog\/wp-content\/uploads\/2024\/09\/cropped-Copia-de-Diseno-sin-titulo.jpg","contentUrl":"https:\/\/adnid.com\/blog\/wp-content\/uploads\/2024\/09\/cropped-Copia-de-Diseno-sin-titulo.jpg","width":600,"height":199,"caption":"ADN Sistemas de Identificaci\u00f3n SL"},"image":{"@id":"https:\/\/adnid.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/adnid.com\/blog\/#\/schema\/person\/f6037a86d189ccc3687f07085cf873b8","name":"Redacci\u00f3n ADNid","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adnid.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/adnid.com\/blog\/wp-content\/litespeed\/avatar\/45edcea2a93e4390bdd93d39721ae1a5.jpg?ver=1787990834","contentUrl":"https:\/\/adnid.com\/blog\/wp-content\/litespeed\/avatar\/45edcea2a93e4390bdd93d39721ae1a5.jpg?ver=1787990834","caption":"Redacci\u00f3n ADNid"},"description":"Especialistas en equipos de etiquetado y AIDC","sameAs":["https:\/\/adnid.com\/"],"url":"https:\/\/adnid.com\/blog\/author\/redaccion-adnid\/"}]}},"_links":{"self":[{"href":"https:\/\/adnid.com\/blog\/wp-json\/wp\/v2\/posts\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adnid.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adnid.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adnid.com\/blog\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/adnid.com\/blog\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":0,"href":"https:\/\/adnid.com\/blog\/wp-json\/wp\/v2\/posts\/7\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adnid.com\/blog\/wp-json\/wp\/v2\/media\/5733"}],"wp:attachment":[{"href":"https:\/\/adnid.com\/blog\/wp-json\/wp\/v2\/media?parent=7"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adnid.com\/blog\/wp-json\/wp\/v2\/categories?post=7"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adnid.com\/blog\/wp-json\/wp\/v2\/tags?post=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}